{"id":1170437,"date":"2025-07-25T00:01:04","date_gmt":"2025-07-24T22:01:04","guid":{"rendered":"https:\/\/puravida-estate.com\/immobilie\/proyecto-moderno-chalet-adosado-de-nueva-construccion-en-la-playa-de-palma-con-piscina-privada-y-azotea\/"},"modified":"2025-07-25T15:53:33","modified_gmt":"2025-07-25T13:53:33","slug":"proyecto-moderno-chalet-adosado-de-nueva-construccion-en-la-playa-de-palma-con-piscina-privada-y-azotea","status":"publish","type":"estate_property","link":"https:\/\/puravida-estate.com\/es\/inmueble\/proyecto-moderno-chalet-adosado-de-nueva-construccion-en-la-playa-de-palma-con-piscina-privada-y-azotea\/","title":{"rendered":"Adosado con 4 dormitorios en Can Pastilla cerca de Palma, nueva construcci\u00f3n con piscina privada"},"content":{"rendered":"<p>Este proyecto de nueva construcci\u00f3n est\u00e1 cerca de la playa, pero c\u00e9ntrico.<br \/>\nSu finalizaci\u00f3n est\u00e1 prevista para 2024 y constar\u00e1 de 26 viviendas adosadas cuyos precios oscilar\u00e1n entre 890.000 y 1.120.000 euros.<br \/>\nA s\u00f3lo 400 metros del mar e influenciadas por la luz mediterr\u00e1nea de Mallorca, las unidades residenciales presentan un dise\u00f1o refinado. Las casas cuentan con acogedores espacios interiores y exteriores, y los pasillos proporcionan un c\u00f3modo enlace entre las zonas de d\u00eda y de noche. La fachada crea un innovador juego volum\u00e9trico, y las unidades residenciales disponen de terrazas sol\u00e1rium privadas y jardines con piscina propia. La sostenibilidad y el compromiso con el medio ambiente se tuvieron en cuenta en todo el proyecto de construcci\u00f3n.<br \/>\nLas habitaciones se abren al exterior a trav\u00e9s de grandes ventanales, lo que proporciona mucha luminosidad y un ambiente \u00fanico. Y para que pueda disfrutar del excelente clima de la isla, el sal\u00f3n de su vivienda conecta con la zona exterior a trav\u00e9s de un jard\u00edn que, junto con el solarium de la azotea, ser\u00e1 sin duda uno de los rincones favoritos de su nuevo hogar.<br \/>\nTodas las casas cuentan con:<br \/>\nAmplio sal\u00f3n-comedor di\u00e1fano de hasta 30 m2. Cocina amueblada y equipada.<br \/>\n3 ba\u00f1os completos (uno en suite).<br \/>\n3 \u00f3 4 dormitorios, seg\u00fan sus necesidades.<br \/>\nDormitorio principal con vestidor.<br \/>\nGran jard\u00edn privado de hasta 130 m2.<br \/>\nPiscina privada.<br \/>\nSolarium en la azotea.<br \/>\nDos plazas de aparcamiento al aire libre.<br \/>\nLas casas est\u00e1n dise\u00f1adas para adaptarse a las necesidades presentes y futuras de cada familia y satisfacer sus preferencias espaciales. Por esta raz\u00f3n, se le ofrecer\u00e1n tres planos diferentes en la planta baja. Puedes elegir entre:<br \/>\n&#8211; Despacho y Cocina Independiente.<br \/>\n&#8211; Despacho y cocina abiertos al sal\u00f3n.<br \/>\n&#8211; Distribuci\u00f3n di\u00e1fana con cocina y sal\u00f3n-comedor en una sola estancia.<\/p>\n<p>Este proyecto de nueva construcci\u00f3n est\u00e1 situado en La Ribera, una zona residencial de Palma, directamente en la playa. S\u00f3lo necesita unos minutos para darse un relajante chapuz\u00f3n en el mar o dar un agradable paseo por la costa mediterr\u00e1nea. Adem\u00e1s, su nuevo hogar est\u00e1 situado en una zona tranquila a s\u00f3lo 15 minutos de la playa. a s\u00f3lo 15 minutos del centro de la ciudad para vivir Palma y 8 minutos del aeropuerto. Rel\u00e1jese con largos paseos por la Podr\u00e1 tumbarse en la playa, darse un chapuz\u00f3n en el mar o disfrutar de los amplios espacios verdes cercanos, sin renunciar a una excelente comunicaci\u00f3n con diversos servicios.<\/p>\n<p>&#8211; w\/c con aire acondicionado<br \/>\n&#8211; TV SAT<br \/>\n&#8211; Internet de alta velocidad<br \/>\n&#8211; piscina<br \/>\n&#8211; soleado<br \/>\n&#8211; brillante<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8230;<\/p>\n","protected":false},"featured_media":1170438,"comment_status":"closed","ping_status":"closed","template":"","property_category":[1368,1233,1232],"property_action_category":[1142,1358],"property_city":[1186],"property_area":[],"property_county_state":[1224],"property_features":[1396,1303,1291,1290,1284,1288,1281,1263,1293],"property_status":[],"class_list":["post-1170437","estate_property","type-estate_property","status-publish","has-post-thumbnail","hentry","property_category-project-es","property_category-proyecto","property_category-villa-es","property_action_category-for-sale-es","property_action_category-se-vende","property_city-can-pastilla-es","property_county_state-palma-y-alrededores","property_features-air-condition-es","property_features-balcony-es","property_features-cable-satellite-tv","property_features-garden-use","property_features-guest-toilet","property_features-open-kitchen-es","property_features-swimming-pool","property_features-lavadero","property_features-washing-drying-room"],"_links":{"self":[{"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/estate_property\/1170437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/estate_property"}],"about":[{"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/types\/estate_property"}],"replies":[{"embeddable":true,"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/comments?post=1170437"}],"version-history":[{"count":0,"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/estate_property\/1170437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/media\/1170438"}],"wp:attachment":[{"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/media?parent=1170437"}],"wp:term":[{"taxonomy":"property_category","embeddable":true,"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/property_category?post=1170437"},{"taxonomy":"property_action_category","embeddable":true,"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/property_action_category?post=1170437"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/property_city?post=1170437"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/property_area?post=1170437"},{"taxonomy":"property_county_state","embeddable":true,"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/property_county_state?post=1170437"},{"taxonomy":"property_features","embeddable":true,"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/property_features?post=1170437"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/puravida-estate.com\/es\/wp-json\/wp\/v2\/property_status?post=1170437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}